
{"id":1309,"date":"2015-12-17T19:14:29","date_gmt":"2015-12-17T17:14:29","guid":{"rendered":"http:\/\/www.accuna.es\/?p=1309"},"modified":"2015-12-17T19:14:29","modified_gmt":"2015-12-17T17:14:29","slug":"el-tsjc-equipara-un-tratamiento-de-reproduccion-asistida-al-embarazo","status":"publish","type":"post","link":"https:\/\/www.accuna.es\/blog\/el-tsjc-equipara-un-tratamiento-de-reproduccion-asistida-al-embarazo\/","title":{"rendered":"El TSJC equipara un tratamiento de reproducci\u00f3n asistida al embarazo"},"content":{"rendered":"<p style=\"text-align: justify;\">La prensa hiz\u00f3 p\u00fablica ayer 16 de diciembre de 2015 la referencia a una reciente <strong><a href=\"http:\/\/ccaa.elpais.com\/ccaa\/2015\/12\/16\/catalunya\/1450284226_954170.html\">Sentencia del Tribunal Superior de Catalu\u00f1a<\/a><\/strong> <strong>que equipara<\/strong>, a efectos de despido de una trabajadora, el hecho de estar sometida a <strong>tratamiento de reproducci\u00f3n asistida<\/strong> <strong>al embarazo<\/strong>, y por tanto, declara nulo el despido efectuado en su d\u00eda por la empresa.<\/p>\n<p style=\"text-align: justify;\">Sin entrar en valoraciones sobre el contenido concreto de la sentencia, llama la atenci\u00f3n el hecho de que el Tribunal considera que\u00a0<strong><em>\u201cEl proceso de <a href=\"\/blog\/no-logro-ser-mama\/#fecundacionvitro\">fecundaci\u00f3n in vitro <\/a>debe ser equiparable a un embarazo real\u201d<\/em> <\/strong>y ello es muy transcendente en otros \u00e1mbitos m\u00e1s all\u00e1 del jur\u00eddico porque \u201cnormaliza\u201d \u2013en el sentido de habitual- que, en ocasiones<strong>, la decisi\u00f3n de ser madre afronta problemas que la medicina puede solucionar,<\/strong> y que esta decisi\u00f3n <strong>y todo el proceso que conlleva encuentra protecci\u00f3n en nuestro sistema jur\u00eddico<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Los <strong><a href=\"\/blog\/no-logro-ser-mama\/\">tratamientos de reproducci\u00f3n asistida<\/a><\/strong> que se practican en la actualidad son cada vez m\u00e1s <strong>sencillos e indoloros<\/strong>. No obstante, exigen un tiempo en visitas, anal\u00edticas y otras pruebas adem\u00e1s del propio tratamiento y consecuencias del mismo, que suponen que la mujer y en menor medida el hombre tengan que ausentarse del trabajo, puesto que habitualmente se realizan en horario laboral. Esta sentencia reconoce y ampara una situaci\u00f3n que provocaba altos niveles de stress incompatible con el propio <strong>tratamiento de reproducci\u00f3n asistida<\/strong> en s\u00ed.<\/p>\n<p style=\"text-align: justify;\">Hoy toca congratularse con la decisi\u00f3n y con las consecuencias que de la misma se derivan. Trae normalidad a un proceso emocionalmente complicado, y que, de alguna manera, desde hoy, es un poco m\u00e1s llevadero.<\/p>\n<p style=\"text-align: justify;\">Desde <strong><a href=\"\/blog\/\">Cl\u00ednica Accuna<\/a><\/strong>, queremos enviar un mensaje de \u00e1nimo a todas las mujeres y todos los hombres que hoy est\u00e1n este proceso. As\u00ed mismo, tambi\u00e9n os recordamos que en nuestra Cl\u00ednica <strong>ofrecemos tratamientos de reproducci\u00f3n asistida con los medios m\u00e1s adecuados y los profesionales m\u00e1s preparados para ayudar a cumplir el deseo de ser madre.<br \/>\nPara conocer los pr\u00f3ximos temas de nuestro <a href=\"\/blog\/blog\/\" target=\"_blank\">blog<\/a>, <a href=\"https:\/\/business.facebook.com\/Accuna.Ginecologia.Fertilidad.Alicante\" target=\"_blank\">s\u00edganos en facebook<\/a> o <a href=\"https:\/\/twitter.com\/AccunaClinica\" target=\"_blank\">twitter<\/a><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prensa hiz\u00f3 p\u00fablica ayer 16 de diciembre de 2015 la referencia a una reciente Sentencia del Tribunal Superior de Catalu\u00f1a que equipara, a efectos de despido de una trabajadora, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1310,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[149],"tags":[2,150,21,141,142,151,152,153],"_links":{"self":[{"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/posts\/1309"}],"collection":[{"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/comments?post=1309"}],"version-history":[{"count":0,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/posts\/1309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/media\/1310"}],"wp:attachment":[{"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/media?parent=1309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/categories?post=1309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.accuna.es\/blog\/wp-json\/wp\/v2\/tags?post=1309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}